{"id":7515,"date":"2020-07-06T12:11:05","date_gmt":"2020-07-06T05:11:05","guid":{"rendered":"https:\/\/www.up18xxx.com\/7515\/"},"modified":"2020-07-06T12:11:05","modified_gmt":"2020-07-06T05:11:05","slug":"%e0%b9%81%e0%b8%ad%e0%b8%9a%e0%b8%9e%e0%b8%b2%e0%b9%80%e0%b8%a1%e0%b8%b5%e0%b8%a2%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%aa%e0%b8%a7%e0%b8%a2%e0%b8%a1%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/www.up18xxx.com\/7515\/","title":{"rendered":"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22"},"content":{"rendered":"<p>\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22 \u0e02\u0e36\u0e49\u0e19\u0e02\u0e22\u0e48\u0e21\u0e04\u0e27\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e34\u0e49\u0e27\u0e04\u0e23\u0e32\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27\u0e15\u0e25\u0e2d\u0e14<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[391,642,641],"class_list":["post-7515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2","tag-391","tag-642","tag-641"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22 - up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.up18xxx.com\/7515\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22 - up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\" \/>\n<meta property=\"og:description\" content=\"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.up18xxx.com\/7515\/\" \/>\n<meta property=\"og:site_name\" content=\"up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-06T05:11:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"330\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.up18xxx.com\/7515\/\",\"url\":\"https:\/\/www.up18xxx.com\/7515\/\",\"name\":\"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22 - up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\",\"isPartOf\":{\"@id\":\"https:\/\/www.up18xxx.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.up18xxx.com\/7515\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.up18xxx.com\/7515\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg\",\"datePublished\":\"2020-07-06T05:11:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.up18xxx.com\/#\/schema\/person\/502ade3162af415853c9668207ef7cb8\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.up18xxx.com\/7515\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.up18xxx.com\/7515\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.up18xxx.com\/7515\/#primaryimage\",\"url\":\"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg\",\"contentUrl\":\"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg\",\"width\":330,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.up18xxx.com\/7515\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.up18xxx.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.up18xxx.com\/#website\",\"url\":\"https:\/\/www.up18xxx.com\/\",\"name\":\"up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\",\"description\":\"\u0e04\u0e25\u0e34\u0e1b\u0e42\u0e1b\u0e4a XXX \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a \u0e2b\u0e19\u0e31\u0e07x \u0e2b\u0e35\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.up18xxx.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.up18xxx.com\/#\/schema\/person\/502ade3162af415853c9668207ef7cb8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.up18xxx.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9c2aa771560dd1374b2651b58130a9330a48ba6a186a274467d0a909a65c7600?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9c2aa771560dd1374b2651b58130a9330a48ba6a186a274467d0a909a65c7600?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.up18xxx.com\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22 - up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.up18xxx.com\/7515\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22 - up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","og_description":"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22...","og_url":"https:\/\/www.up18xxx.com\/7515\/","og_site_name":"up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","article_published_time":"2020-07-06T05:11:05+00:00","og_image":[{"width":330,"height":185,"url":"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.up18xxx.com\/7515\/","url":"https:\/\/www.up18xxx.com\/7515\/","name":"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22 - up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","isPartOf":{"@id":"https:\/\/www.up18xxx.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.up18xxx.com\/7515\/#primaryimage"},"image":{"@id":"https:\/\/www.up18xxx.com\/7515\/#primaryimage"},"thumbnailUrl":"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg","datePublished":"2020-07-06T05:11:05+00:00","author":{"@id":"https:\/\/www.up18xxx.com\/#\/schema\/person\/502ade3162af415853c9668207ef7cb8"},"breadcrumb":{"@id":"https:\/\/www.up18xxx.com\/7515\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.up18xxx.com\/7515\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.up18xxx.com\/7515\/#primaryimage","url":"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg","contentUrl":"https:\/\/www.up18xxx.com\/wp-content\/uploads\/2020\/07\/7515.jpg","width":330,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/www.up18xxx.com\/7515\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.up18xxx.com\/"},{"@type":"ListItem","position":2,"name":"\u0e41\u0e2d\u0e1a\u0e1e\u0e32\u0e40\u0e21\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e2a\u0e27\u0e22\u0e21\u0e32\u0e40\u0e22\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e25\u0e35\u0e25\u0e32\u0e42\u0e21\u0e4a\u0e01\u0e04\u0e27\u0e22\u0e40\u0e14\u0e47\u0e14\u0e21\u0e32\u0e01 \u0e19\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/www.up18xxx.com\/#website","url":"https:\/\/www.up18xxx.com\/","name":"up18xxx \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a\u0e40\u0e22\u0e2d\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","description":"\u0e04\u0e25\u0e34\u0e1b\u0e42\u0e1b\u0e4a XXX \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e1b\u0e4a \u0e2b\u0e19\u0e31\u0e07x \u0e2b\u0e35","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.up18xxx.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.up18xxx.com\/#\/schema\/person\/502ade3162af415853c9668207ef7cb8","name":"admin","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.up18xxx.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9c2aa771560dd1374b2651b58130a9330a48ba6a186a274467d0a909a65c7600?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c2aa771560dd1374b2651b58130a9330a48ba6a186a274467d0a909a65c7600?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.up18xxx.com\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/posts\/7515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/comments?post=7515"}],"version-history":[{"count":0,"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/posts\/7515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/media\/7516"}],"wp:attachment":[{"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/media?parent=7515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/categories?post=7515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.up18xxx.com\/wp-json\/wp\/v2\/tags?post=7515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}